{"id":172,"date":"2016-05-06T16:08:30","date_gmt":"2016-05-06T16:08:30","guid":{"rendered":"http:\/\/lab1.shufflehound.com\/experiments\/?post_type=fw-portfolio&#038;p=172"},"modified":"2021-10-19T05:14:16","modified_gmt":"2021-10-19T05:14:16","slug":"video-sec","status":"publish","type":"fw-portfolio","link":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/","title":{"rendered":"VIDEO-SEC"},"content":{"rendered":"<div id=\"pgc-1725-1-0\" class=\"panel-grid-cell\">\n<div id=\"panel-1725-1-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"1\">\n<div class=\"textwidget\">\n<h2>EVIDENCIA INDISPUTABLE OBTENIDA CON VIDEO-SEC DE NOVOAGLOBAL<\/h2>\n<p>Cuando un oficial investiga la causa de un accidente o un detective enfrenta un crimen sin resolver, un video claro de alta resoluci\u00f3n hace toda la diferencia.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p><a href=\"https:\/\/novoaglobal.com\/es\/video-sec\/\"><button style=\" background-color: #3b54a1; border:none; color:white; border-radius: 100px; height: 50px; padding: 0 30px 0 20px; margin-right: 5px;     margin-bottom: 5px; \"><strong>Leer M\u00e1s<\/strong><\/button><\/a><\/p>\n","protected":false},"featured_media":5802,"comment_status":"closed","ping_status":"closed","template":"","fw-portfolio-category":[74,73,71,72],"class_list":["post-172","fw-portfolio","type-fw-portfolio","status-publish","has-post-thumbnail","hentry","fw-portfolio-category-ciudad-inteligente","fw-portfolio-category-ciudad-segura","fw-portfolio-category-seguridad-publica","fw-portfolio-category-soluciones-integradas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monitoreo y Grabaci\u00f3n en Video con bajo requerimiento de ancho de banda<\/title>\n<meta name=\"description\" content=\"NovoaGlobal\u2122 ofrece monitoreo de videovigilancia de tr\u00e1nsito en tiempo casi real las 24 horas, los 7 d\u00edas de la semana para mejorar el control de tr\u00e1nsito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novoaglobal.com\/es\/project\/video-sec\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monitoreo y Grabaci\u00f3n en Video con bajo requerimiento de ancho de banda\" \/>\n<meta property=\"og:description\" content=\"NovoaGlobal\u2122 ofrece monitoreo de videovigilancia de tr\u00e1nsito en tiempo casi real las 24 horas, los 7 d\u00edas de la semana para mejorar el control de tr\u00e1nsito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novoaglobal.com\/es\/project\/video-sec\/\" \/>\n<meta property=\"og:site_name\" content=\"NovoaGlobal\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/novoaglobal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-19T05:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2016\/05\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NovoaGlobal\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/\",\"url\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/\",\"name\":\"Monitoreo y Grabaci\u00f3n en Video con bajo requerimiento de ancho de banda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg\",\"datePublished\":\"2016-05-06T16:08:30+00:00\",\"dateModified\":\"2021-10-19T05:14:16+00:00\",\"description\":\"NovoaGlobal\u2122 ofrece monitoreo de videovigilancia de tr\u00e1nsito en tiempo casi real las 24 horas, los 7 d\u00edas de la semana para mejorar el control de tr\u00e1nsito.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/#primaryimage\",\"url\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg\",\"contentUrl\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg\",\"width\":1000,\"height\":635},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/video-sec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VIDEO-SEC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/\",\"name\":\"NovoaGlobal\u2122\",\"description\":\"Creando comunidades m\u00e1s seguras\",\"publisher\":{\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/#organization\",\"name\":\"NovoaGlobal\",\"url\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo-history-2.png\",\"contentUrl\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/logo-history-2.png\",\"width\":394,\"height\":363,\"caption\":\"NovoaGlobal\"},\"image\":{\"@id\":\"https:\\\/\\\/novoaglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/novoaglobal\\\/\",\"https:\\\/\\\/x.com\\\/NovoaGlobal\",\"https:\\\/\\\/www.instagram.com\\\/novoaglobal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/novoaglobal\\\/about\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCoMVz-xMzL_dyjZ0GgVz7Dw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monitoreo y Grabaci\u00f3n en Video con bajo requerimiento de ancho de banda","description":"NovoaGlobal\u2122 ofrece monitoreo de videovigilancia de tr\u00e1nsito en tiempo casi real las 24 horas, los 7 d\u00edas de la semana para mejorar el control de tr\u00e1nsito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/","og_locale":"es_ES","og_type":"article","og_title":"Monitoreo y Grabaci\u00f3n en Video con bajo requerimiento de ancho de banda","og_description":"NovoaGlobal\u2122 ofrece monitoreo de videovigilancia de tr\u00e1nsito en tiempo casi real las 24 horas, los 7 d\u00edas de la semana para mejorar el control de tr\u00e1nsito.","og_url":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/","og_site_name":"NovoaGlobal\u00ae","article_publisher":"https:\/\/www.facebook.com\/novoaglobal\/","article_modified_time":"2021-10-19T05:14:16+00:00","og_image":[{"width":1000,"height":635,"url":"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2016\/05\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@NovoaGlobal","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/","url":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/","name":"Monitoreo y Grabaci\u00f3n en Video con bajo requerimiento de ancho de banda","isPartOf":{"@id":"https:\/\/novoaglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/#primaryimage"},"image":{"@id":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/#primaryimage"},"thumbnailUrl":"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2016\/05\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg","datePublished":"2016-05-06T16:08:30+00:00","dateModified":"2021-10-19T05:14:16+00:00","description":"NovoaGlobal\u2122 ofrece monitoreo de videovigilancia de tr\u00e1nsito en tiempo casi real las 24 horas, los 7 d\u00edas de la semana para mejorar el control de tr\u00e1nsito.","breadcrumb":{"@id":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novoaglobal.com\/es\/project\/video-sec\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/#primaryimage","url":"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2016\/05\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg","contentUrl":"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2016\/05\/NG-School-Zone-Speed-Web-Solutions_edited-2-smaller-for-the-web.jpg","width":1000,"height":635},{"@type":"BreadcrumbList","@id":"https:\/\/novoaglobal.com\/es\/project\/video-sec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/novoaglobal.com\/es\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/novoaglobal.com\/es\/project\/"},{"@type":"ListItem","position":3,"name":"VIDEO-SEC"}]},{"@type":"WebSite","@id":"https:\/\/novoaglobal.com\/es\/#website","url":"https:\/\/novoaglobal.com\/es\/","name":"NovoaGlobal\u2122","description":"Creando comunidades m\u00e1s seguras","publisher":{"@id":"https:\/\/novoaglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novoaglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/novoaglobal.com\/es\/#organization","name":"NovoaGlobal","url":"https:\/\/novoaglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/novoaglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2019\/10\/logo-history-2.png","contentUrl":"https:\/\/novoaglobal.com\/es\/wp-content\/uploads\/2019\/10\/logo-history-2.png","width":394,"height":363,"caption":"NovoaGlobal"},"image":{"@id":"https:\/\/novoaglobal.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/novoaglobal\/","https:\/\/x.com\/NovoaGlobal","https:\/\/www.instagram.com\/novoaglobal\/","https:\/\/www.linkedin.com\/company\/novoaglobal\/about\/","https:\/\/www.youtube.com\/channel\/UCoMVz-xMzL_dyjZ0GgVz7Dw"]}]}},"_links":{"self":[{"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/fw-portfolio\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/fw-portfolio"}],"about":[{"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/types\/fw-portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":1,"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/fw-portfolio\/172\/revisions"}],"predecessor-version":[{"id":10408,"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/fw-portfolio\/172\/revisions\/10408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/media\/5802"}],"wp:attachment":[{"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"fw-portfolio-category","embeddable":true,"href":"https:\/\/novoaglobal.com\/es\/wp-json\/wp\/v2\/fw-portfolio-category?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}